{"id":1861,"date":"2022-10-25T13:27:11","date_gmt":"2022-10-25T13:27:11","guid":{"rendered":"http:\/\/howtowindowsguides.com\/come-aprire-gestione-disco-in-windows-10\/"},"modified":"2022-11-14T15:23:24","modified_gmt":"2022-11-14T15:23:24","slug":"come-aprire-gestione-disco-in-windows-10","status":"publish","type":"post","link":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/","title":{"rendered":"Come aprire Gestione disco in Windows 10"},"content":{"rendered":"<p><strong>Gestione disco<\/strong> \u00e8 un&#8217;utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi e sui relativi volumi e partizioni.<\/p>\n<p>Lo strumento Gestione disco consente di definire la capacit\u00e0 totale, lo spazio libero, lo stato e altre propriet\u00e0 dei dischi, di creare partizioni e dischi logici su dischi di base, di creare volumi su dischi dinamici, di espandere i volumi per aumentarne le dimensioni, di formattare i volumi con il file system selezionato, di assegnare lettere di unit\u00e0 e percorsi di volume, di convertire dischi di base in dinamici e viceversa.<\/p>\n<h2>Avviare nella finestra Esegui<\/h2>\n<p>Aprire la finestra di dialogo Esegui premendo <mark><br \/>\n  <strong>Win+R<\/strong><br \/>\n<\/mark>, nella finestra <strong>Esegui<\/strong> digitare (copiare e incollare) <strong><br \/>\n  <em>diskmgmt.msc<\/em><br \/>\n<\/strong> e fare clic su <mark><br \/>\n  <strong>OK<\/strong><br \/>\n<\/mark>.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1523\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_1-1.jpg\" alt=\"\" width=\"399\" height=\"206\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_1-1.jpg 399w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_1-1-300x155.jpg 300w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><meta itemprop=\"width\" content=\"399\"><meta itemprop=\"height\" content=\"206\"><\/span><\/p>\n<h2>Come aprire tramite il menu Win+X (menu Power User)<\/h2>\n<p>\u00c8 possibile accedere allo snap-in Gestione disco anche tramite &#8220;Win+X&#8221; (Power User Menu), facendo clic con il pulsante destro del mouse sul tasto <strong><br \/>\n  <mark>Avvio<\/mark><br \/>\n<\/strong> sulla barra delle applicazioni o premendo <mark><br \/>\n  <strong>Win+X<\/strong><br \/>\n<\/mark> e selezionare Gestione disco nel menu visualizzato.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1527\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_2-1.jpg\" alt=\"\" width=\"297\" height=\"649\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_2-1.jpg 297w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_2-1-137x300.jpg 137w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_2-1-183x400.jpg 183w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><meta itemprop=\"width\" content=\"297\"><meta itemprop=\"height\" content=\"649\"><\/span><\/p>\n<h2>Aprire Gestione disco con il Finder di Windows<\/h2>\n<p>Per aprire Gestione disco, utilizzare la <strong>Ricerca in Windows<\/strong> facendo clic sull&#8217;icona di ricerca nella barra delle applicazioni oppure premere <mark><br \/>\n  <strong>Win+S<\/strong><br \/>\n<\/mark>, digitare diskmgmt.msc nella casella di ricerca e selezionare <em><br \/>\n  <strong>diskmgmt.ms<\/strong><br \/>\n<\/em>c nei risultati della ricerca.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1531\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_3-1.jpg\" alt=\"\" width=\"855\" height=\"695\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_3-1.jpg 855w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_3-1-300x244.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_3-1-768x624.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_3-1-492x400.jpg 492w\" sizes=\"auto, (max-width: 855px) 100vw, 855px\" \/><meta itemprop=\"width\" content=\"855\"><meta itemprop=\"height\" content=\"695\"><\/span><\/p>\n<h2>Esecuzione del file nella directory di sistema System32<\/h2>\n<p>Aprire Windows Explorer e navigare nel seguente percorso:<\/p>\n<blockquote><p>C:\\Windows\\System32<\/p><\/blockquote>\n<p>Fare doppio clic <mark><br \/>\n  <strong>diskmgmt.msc<\/strong><br \/>\n<\/mark> per aprire lo snap-in Gestione disco<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1535\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_4-1.jpg\" alt=\"\" width=\"1022\" height=\"575\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_4-1.jpg 1022w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_4-1-300x169.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_4-1-768x432.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_4-1-711x400.jpg 711w\" sizes=\"auto, (max-width: 1022px) 100vw, 1022px\" \/><meta itemprop=\"width\" content=\"1022\"><meta itemprop=\"height\" content=\"575\"><\/span><\/p>\n<h2>Utilizzare il prompt dei comandi o Windows PowerShell<\/h2>\n<p>Avviare un prompt dei comandi ed eseguire il seguente comando<\/p>\n<blockquote><p>diskmgmt.msc<\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1539\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_5-1.jpg\" alt=\"\" width=\"979\" height=\"512\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_5-1.jpg 979w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_5-1-300x157.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_5-1-768x402.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_5-1-765x400.jpg 765w\" sizes=\"auto, (max-width: 979px) 100vw, 979px\" \/><meta itemprop=\"width\" content=\"979\"><meta itemprop=\"height\" content=\"512\"><\/span><\/p>\n<p>Aprite la console di Windows PowerShell ed eseguite il seguente comando:<\/p>\n<blockquote><p>diskmgmt.msc<\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1543\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_6.jpg\" alt=\"\" width=\"886\" height=\"387\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_6.jpg 886w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_6-300x131.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_6-768x335.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot_6-870x380.jpg 870w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><meta itemprop=\"width\" content=\"886\"><meta itemprop=\"height\" content=\"387\"><\/span><\/p>\n<p>Utilizzando i metodi discussi in precedenza, \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestione disco \u00e8 un&#8217;utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi e sui relativi volumi e partizioni. Lo strumento Gestione disco consente di definire la capacit\u00e0 totale, lo spazio libero, lo stato e altre propriet\u00e0 dei dischi, di creare partizioni e dischi logici su [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[],"class_list":["post-1861","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-instructions","category-windows-powershell"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come aprire Gestione disco in Windows 10<\/title>\n<meta name=\"description\" content=\"Questo articolo illustra i diversi modi in cui \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10. &quot;Gestione disco \u00e8 un&#039;utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi, sui volumi e sulle partizioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come aprire Gestione disco in Windows 10\" \/>\n<meta property=\"og:description\" content=\"Questo articolo illustra i diversi modi in cui \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10. &quot;Gestione disco \u00e8 un&#039;utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi, sui volumi e sulle partizioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T13:27:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-14T15:23:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1103\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oliver Bennett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oliver Bennett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/\"},\"author\":{\"name\":\"Oliver Bennett\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"headline\":\"Come aprire Gestione disco in Windows 10\",\"datePublished\":\"2022-10-25T13:27:11+00:00\",\"dateModified\":\"2022-11-14T15:23:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/\"},\"wordCount\":306,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenshot-1.jpg\",\"articleSection\":[\"Instructions\",\"Windows PowerShell\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/\",\"name\":\"Come aprire Gestione disco in Windows 10\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenshot-1.jpg\",\"datePublished\":\"2022-10-25T13:27:11+00:00\",\"dateModified\":\"2022-11-14T15:23:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"description\":\"Questo articolo illustra i diversi modi in cui \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10. \\\"Gestione disco \u00e8 un'utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi, sui volumi e sulle partizioni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenshot-1.jpg\",\"contentUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenshot-1.jpg\",\"width\":1103,\"height\":727},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-aprire-gestione-disco-in-windows-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come aprire Gestione disco in Windows 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\",\"name\":\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\",\"name\":\"Oliver Bennett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"caption\":\"Oliver Bennett\"},\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/author\\\/oliver\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come aprire Gestione disco in Windows 10","description":"Questo articolo illustra i diversi modi in cui \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10. \"Gestione disco \u00e8 un'utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi, sui volumi e sulle partizioni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/","og_locale":"it_IT","og_type":"article","og_title":"Come aprire Gestione disco in Windows 10","og_description":"Questo articolo illustra i diversi modi in cui \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10. \"Gestione disco \u00e8 un'utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi, sui volumi e sulle partizioni.","og_url":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/","og_site_name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","article_published_time":"2022-10-25T13:27:11+00:00","article_modified_time":"2022-11-14T15:23:24+00:00","og_image":[{"width":1103,"height":727,"url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot-1.jpg","type":"image\/jpeg"}],"author":"Oliver Bennett","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Oliver Bennett","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#article","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/"},"author":{"name":"Oliver Bennett","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"headline":"Come aprire Gestione disco in Windows 10","datePublished":"2022-10-25T13:27:11+00:00","dateModified":"2022-11-14T15:23:24+00:00","mainEntityOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/"},"wordCount":306,"commentCount":0,"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot-1.jpg","articleSection":["Instructions","Windows PowerShell"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/","url":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/","name":"Come aprire Gestione disco in Windows 10","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#primaryimage"},"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot-1.jpg","datePublished":"2022-10-25T13:27:11+00:00","dateModified":"2022-11-14T15:23:24+00:00","author":{"@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"description":"Questo articolo illustra i diversi modi in cui \u00e8 possibile aprire lo snap-in di Gestione disco in Windows 10. \"Gestione disco \u00e8 un'utilit\u00e0 con interfaccia grafica integrata nel sistema operativo che pu\u00f2 essere utilizzata per eseguire varie operazioni sui dischi rigidi, sui volumi e sulle partizioni.","breadcrumb":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#primaryimage","url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot-1.jpg","contentUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/10\/screenshot-1.jpg","width":1103,"height":727},{"@type":"BreadcrumbList","@id":"https:\/\/howtowindowsguides.com\/it\/come-aprire-gestione-disco-in-windows-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtowindowsguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come aprire Gestione disco in Windows 10"}]},{"@type":"WebSite","@id":"https:\/\/howtowindowsguides.com\/it\/#website","url":"https:\/\/howtowindowsguides.com\/it\/","name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtowindowsguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31","name":"Oliver Bennett","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","caption":"Oliver Bennett"},"url":"https:\/\/howtowindowsguides.com\/it\/author\/oliver\/"}]}},"_links":{"self":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/comments?post=1861"}],"version-history":[{"count":0,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media\/1521"}],"wp:attachment":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media?parent=1861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/categories?post=1861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/tags?post=1861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}