{"id":1669,"date":"2022-10-25T13:14:20","date_gmt":"2022-10-25T13:14:20","guid":{"rendered":"http:\/\/howtowindowsguides.com\/?p=1669"},"modified":"2023-03-13T10:34:08","modified_gmt":"2023-03-13T10:34:08","slug":"come-attivare-la-modalita-prestazioni-massime-in-windows-10","status":"publish","type":"post","link":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/","title":{"rendered":"Come attivare la modalit\u00e0 prestazioni massime in Windows 10"},"content":{"rendered":"<p>Il sistema operativo Windows prevede tre schemi di alimentazione: bilanciato, a risparmio energetico e ad alte prestazioni. Con il rilascio della versione 1803 di Windows 10, gli sviluppatori di Microsoft hanno aggiunto un altro schema di potenza chiamato <mark><br \/>\n  <strong>Prestazioni massime<\/strong><br \/>\n<\/mark>.<\/p>\n<p>La modalit\u00e0 Ultimate Performance assicura un livello elevato di prestazioni del dispositivo eliminando la cosiddetta micro latenza associata alla potenza del computer, il che significa che con l&#8217;aumento della potenza di calcolo del dispositivo, aumenter\u00e0 anche la quantit\u00e0 di energia consumata dal dispositivo.<\/p>\n<p>La modalit\u00e0 di prestazioni massime \u00e8 particolarmente utile per ingegneri, programmatori e altri utenti che utilizzano il computer per l&#8217;editing video, il rendering 3D e altre attivit\u00e0 di calcolo impegnative.<\/p>\n<p>Questo schema di alimentazione \u00e8 disponibile in Windows 10 Pro for Workstations, ma pu\u00f2 essere facilmente attivato in qualsiasi edizione di Windows 10, se necessario.<\/p>\n<h2>Come attivare la modalit\u00e0 prestazioni massime<\/h2>\n<p>Per attivare la modalit\u00e0 prestazioni massime, eseguire la riga di comando o la console Windows PowerShell come amministratore ed eseguire il seguente comando:<\/p>\n<blockquote><p>powercfg -duplicatescheme e9a42b02-d5df-448d-aa00-03f14749eb61<\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1091\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_1.jpg\" alt=\"\" width=\"882\" height=\"278\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_1.jpg 882w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_1-300x95.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_1-768x242.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_1-870x274.jpg 870w\" sizes=\"auto, (max-width: 882px) 100vw, 882px\" \/><meta itemprop=\"width\" content=\"882\"><meta itemprop=\"height\" content=\"278\"><\/span><\/p>\n<p>Ora vada nelle impostazioni dell&#8217;alimentatore e <mark><br \/>\n  <strong>Ultimate Performance<\/strong><br \/>\n<\/mark> appare nei diagrammi aggiuntivi; se necessario, lo attivi impostando l&#8217;interruttore nella posizione appropriata, cliccando sul cerchio.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1095\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_2.jpg\" alt=\"\" width=\"1047\" height=\"640\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_2.jpg 1047w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_2-300x183.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_2-1024x626.jpg 1024w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_2-768x469.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_2-654x400.jpg 654w\" sizes=\"auto, (max-width: 1047px) 100vw, 1047px\" \/><meta itemprop=\"width\" content=\"1047\"><meta itemprop=\"height\" content=\"640\"><\/span><\/p>\n<h2>Come disattivare la modalit\u00e0 prestazioni massime<\/h2>\n<p>Per disattivare la modalit\u00e0 prestazioni massime, eseguire la riga di comando o la console Windows PowerShell come amministratore ed eseguire il seguente comando:<\/p>\n<blockquote><p>powercfg -restoredefaultschemes<\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1099\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_3.jpg\" alt=\"\" width=\"896\" height=\"254\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_3.jpg 896w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_3-300x85.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_3-768x218.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot_3-870x247.jpg 870w\" sizes=\"auto, (max-width: 896px) 100vw, 896px\" \/><meta itemprop=\"width\" content=\"896\"><meta itemprop=\"height\" content=\"254\"><\/span><\/p>\n<p>Utilizzando i passaggi sopra descritti, \u00e8 possibile attivare o disattivare la Modalit\u00e0 Prestazioni Ultimate in Windows 10.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sistema operativo Windows prevede tre schemi di alimentazione: bilanciato, a risparmio energetico e ad alte prestazioni. Con il rilascio della versione 1803 di Windows 10, gli sviluppatori di Microsoft hanno aggiunto un altro schema di potenza chiamato Prestazioni massime . La modalit\u00e0 Ultimate Performance assicura un livello elevato di prestazioni del dispositivo eliminando la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,43],"tags":[],"class_list":["post-1669","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-istruzioni","category-windows-powershell-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come attivare la modalit\u00e0 prestazioni massime in Windows 10<\/title>\n<meta name=\"description\" content=\"Questo articolo mostra come utilizzare la console di Windows PowerShell per attivare la modalit\u00e0 prestazioni massime.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come attivare la modalit\u00e0 prestazioni massime in Windows 10\" \/>\n<meta property=\"og:description\" content=\"Questo articolo mostra come utilizzare la console di Windows PowerShell per attivare la modalit\u00e0 prestazioni massime.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T13:14:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T10:34:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1183\" \/>\n\t<meta property=\"og:image:height\" content=\"729\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oliver Bennett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oliver Bennett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/\"},\"author\":{\"name\":\"Oliver Bennett\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"headline\":\"Come attivare la modalit\u00e0 prestazioni massime in Windows 10\",\"datePublished\":\"2022-10-25T13:14:20+00:00\",\"dateModified\":\"2023-03-13T10:34:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/\"},\"wordCount\":254,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/screenshot.jpg\",\"articleSection\":[\"Istruzioni\",\"Windows PowerShell\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/\",\"name\":\"Come attivare la modalit\u00e0 prestazioni massime in Windows 10\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/screenshot.jpg\",\"datePublished\":\"2022-10-25T13:14:20+00:00\",\"dateModified\":\"2023-03-13T10:34:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"description\":\"Questo articolo mostra come utilizzare la console di Windows PowerShell per attivare la modalit\u00e0 prestazioni massime.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/screenshot.jpg\",\"contentUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/screenshot.jpg\",\"width\":1183,\"height\":729},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come attivare la modalit\u00e0 prestazioni massime in Windows 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\",\"name\":\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\",\"name\":\"Oliver Bennett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"caption\":\"Oliver Bennett\"},\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/author\\\/oliver\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come attivare la modalit\u00e0 prestazioni massime in Windows 10","description":"Questo articolo mostra come utilizzare la console di Windows PowerShell per attivare la modalit\u00e0 prestazioni massime.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/","og_locale":"it_IT","og_type":"article","og_title":"Come attivare la modalit\u00e0 prestazioni massime in Windows 10","og_description":"Questo articolo mostra come utilizzare la console di Windows PowerShell per attivare la modalit\u00e0 prestazioni massime.","og_url":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/","og_site_name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","article_published_time":"2022-10-25T13:14:20+00:00","article_modified_time":"2023-03-13T10:34:08+00:00","og_image":[{"width":1183,"height":729,"url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot.jpg","type":"image\/jpeg"}],"author":"Oliver Bennett","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Oliver Bennett","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#article","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/"},"author":{"name":"Oliver Bennett","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"headline":"Come attivare la modalit\u00e0 prestazioni massime in Windows 10","datePublished":"2022-10-25T13:14:20+00:00","dateModified":"2023-03-13T10:34:08+00:00","mainEntityOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/"},"wordCount":254,"commentCount":0,"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot.jpg","articleSection":["Istruzioni","Windows PowerShell"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/","url":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/","name":"Come attivare la modalit\u00e0 prestazioni massime in Windows 10","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#primaryimage"},"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot.jpg","datePublished":"2022-10-25T13:14:20+00:00","dateModified":"2023-03-13T10:34:08+00:00","author":{"@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"description":"Questo articolo mostra come utilizzare la console di Windows PowerShell per attivare la modalit\u00e0 prestazioni massime.","breadcrumb":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#primaryimage","url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot.jpg","contentUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/09\/screenshot.jpg","width":1183,"height":729},{"@type":"BreadcrumbList","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-la-modalita-prestazioni-massime-in-windows-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtowindowsguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come attivare la modalit\u00e0 prestazioni massime in Windows 10"}]},{"@type":"WebSite","@id":"https:\/\/howtowindowsguides.com\/it\/#website","url":"https:\/\/howtowindowsguides.com\/it\/","name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtowindowsguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31","name":"Oliver Bennett","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","caption":"Oliver Bennett"},"url":"https:\/\/howtowindowsguides.com\/it\/author\/oliver\/"}]}},"_links":{"self":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/comments?post=1669"}],"version-history":[{"count":0,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media\/1089"}],"wp:attachment":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media?parent=1669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/categories?post=1669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/tags?post=1669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}