{"id":1478,"date":"2022-10-03T08:57:35","date_gmt":"2022-10-03T08:57:35","guid":{"rendered":"http:\/\/howtowindowsguides.com\/?p=1478"},"modified":"2022-10-03T08:58:14","modified_gmt":"2022-10-03T08:58:14","slug":"come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10","status":"publish","type":"post","link":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/","title":{"rendered":"Come disinstallare una macchina virtuale Hyper-V in Windows 10"},"content":{"rendered":"<p>La piattaforma <strong>Hyper-V<\/strong> consente di eseguire sistemi informatici virtualizzati su un host fisico. Questi sistemi virtualizzati (sistemi guest) possono essere utilizzati e gestiti come se fossero sistemi informatici fisici, ma esistono in un ambiente virtualizzato e isolato,<\/p>\n<p>Una macchina virtuale Hyper-V pu\u00f2 essere disinstallata se necessario e la macchina virtuale viene disinstallata solo dal gestore Hyper-V.<\/p>\n<p>La disinstallazione di una macchina virtuale Hyper-V elimina il file di configurazione della macchina virtuale, ma non elimina i dischi rigidi virtuali (file).<mark><br \/>\n<strong>.VHDX<\/strong><br \/>\n<\/mark> file).<\/p>\n<p>Se la macchina virtuale ha dei punti di controllo (snapshot), questi vengono rimossi e uniti ai file del disco rigido virtuale dopo la rimozione della macchina virtuale.<\/p>\n<h2>Come disinstallare una macchina virtuale Hyper-V in &#8220;Gestione Hyper-V&#8221;.<\/h2>\n<p>Per rimuovere una macchina virtuale, aprire Hyper-V Manager (<mark><br \/>\n<strong>virtmgmt.msc<\/strong><br \/>\n<\/mark>).<\/p>\n<p>Nell&#8217;elenco delle macchine virtuali installate, selezionare la macchina virtuale Hyper-V che si desidera rimuovere (in questo esempio, Windows 11) ed eseguire una delle seguenti operazioni:<\/p>\n<ul>\n<li>Fare clic con il tasto destro del mouse sulla macchina virtuale selezionata e selezionare <mark><br \/>\n<strong>Disinstallare&#8230;<\/strong><br \/>\n<\/mark> dal menu contestuale visualizzato.<\/li>\n<li>Nell&#8217;angolo in basso a destra della barra delle azioni, selezionare <mark><strong>Elimina<\/strong><\/mark>&#8230;<\/li>\n<li>Premete il tasto <mark><br \/>\n<strong>Del<\/strong><br \/>\n<\/mark> sulla tastiera.<\/li>\n<\/ul>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-846\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_1-1.jpg\" alt=\"\" width=\"953\" height=\"620\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_1-1.jpg 953w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_1-1-300x195.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_1-1-768x500.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_1-1-615x400.jpg 615w\" sizes=\"auto, (max-width: 953px) 100vw, 953px\" \/><meta itemprop=\"width\" content=\"953\"><meta itemprop=\"height\" content=\"620\"><\/span><\/p>\n<p>Quando viene richiesto di disinstallare la macchina virtuale, fare clic sul pulsante <mark><br \/>\n<strong>Eliminazione<\/strong><br \/>\n<\/mark> .<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-850\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_2-1.jpg\" alt=\"\" width=\"385\" height=\"155\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_2-1.jpg 385w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_2-1-300x121.jpg 300w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><meta itemprop=\"width\" content=\"385\"><meta itemprop=\"height\" content=\"155\"><\/span><\/p>\n<h2>Come disinstallare una macchina virtuale Hyper-V in Windows PowerShell<\/h2>\n<p>\u00c8 anche possibile disinstallare una macchina virtuale utilizzando la console di Windows PowerShell.<\/p>\n<p>Prima di disinstallare una macchina virtuale, elenchiamo le macchine virtuali disponibili aprendo la console di Windows PowerShell come amministratore ed eseguendo il comando:<\/p>\n<blockquote><p>Ottieni-VM<\/p><\/blockquote>\n<p>Ricordate il nome della macchina virtuale che volete disinstallare (in questo esempio disinstalleremo la macchina virtuale denominata Windows 11).<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-859\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_3.jpg\" alt=\"\" width=\"869\" height=\"399\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_3.jpg 869w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_3-300x138.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_3-768x353.jpg 768w\" sizes=\"auto, (max-width: 869px) 100vw, 869px\" \/><meta itemprop=\"width\" content=\"869\"><meta itemprop=\"height\" content=\"399\"><\/span><\/p>\n<p>Per eliminare una macchina virtuale, eseguire il seguente comando:<\/p>\n<blockquote><p><strong>Rimuovi-VM &#8220;<\/strong><em>Nome_macchina_virtuale<\/em><strong>&#8221; -Forza<\/strong><\/p><\/blockquote>\n<p>Sostituire il nome della <em>macchina virtuale<\/em> nel comando precedente con il nome effettivo della macchina virtuale che si desidera rimuovere (Windows 11 in questo esempio).<\/p>\n<p>In questo esempio, il comando si presenta come segue<\/p>\n<blockquote><p>Rimuovi-VM &#8220;Windows 11&#8221; -Forza<\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-863\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_4.jpg\" alt=\"\" width=\"875\" height=\"402\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_4.jpg 875w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_4-300x138.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_4-768x353.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot_4-870x400.jpg 870w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><meta itemprop=\"width\" content=\"875\"><meta itemprop=\"height\" content=\"402\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La piattaforma Hyper-V consente di eseguire sistemi informatici virtualizzati su un host fisico. Questi sistemi virtualizzati (sistemi guest) possono essere utilizzati e gestiti come se fossero sistemi informatici fisici, ma esistono in un ambiente virtualizzato e isolato, Una macchina virtuale Hyper-V pu\u00f2 essere disinstallata se necessario e la macchina virtuale viene disinstallata solo dal gestore [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[],"class_list":["post-1478","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-instructions","category-windows-powershell"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come disinstallare una macchina virtuale Hyper-V in Windows 10<\/title>\n<meta name=\"description\" content=\"Informazioni per l&#039;inserimento di una macchina virtuale in Hyper-V con Hyper-V Manager o Windows PowerShell.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come disinstallare una macchina virtuale Hyper-V in Windows 10\" \/>\n<meta property=\"og:description\" content=\"Informazioni per l&#039;inserimento di una macchina virtuale in Hyper-V con Hyper-V Manager o Windows PowerShell.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-03T08:57:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-03T08:58:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"953\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oliver Bennett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oliver Bennett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/\"},\"author\":{\"name\":\"Oliver Bennett\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"headline\":\"Come disinstallare una macchina virtuale Hyper-V in Windows 10\",\"datePublished\":\"2022-10-03T08:57:35+00:00\",\"dateModified\":\"2022-10-03T08:58:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/\"},\"wordCount\":323,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/screenshot-1.jpg\",\"articleSection\":[\"Instructions\",\"Windows PowerShell\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/\",\"name\":\"Come disinstallare una macchina virtuale Hyper-V in Windows 10\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/screenshot-1.jpg\",\"datePublished\":\"2022-10-03T08:57:35+00:00\",\"dateModified\":\"2022-10-03T08:58:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"description\":\"Informazioni per l'inserimento di una macchina virtuale in Hyper-V con Hyper-V Manager o Windows PowerShell.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/screenshot-1.jpg\",\"contentUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/screenshot-1.jpg\",\"width\":953,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come disinstallare una macchina virtuale Hyper-V in Windows 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\",\"name\":\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\",\"name\":\"Oliver Bennett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"caption\":\"Oliver Bennett\"},\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/author\\\/oliver\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come disinstallare una macchina virtuale Hyper-V in Windows 10","description":"Informazioni per l'inserimento di una macchina virtuale in Hyper-V con Hyper-V Manager o Windows PowerShell.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/","og_locale":"it_IT","og_type":"article","og_title":"Come disinstallare una macchina virtuale Hyper-V in Windows 10","og_description":"Informazioni per l'inserimento di una macchina virtuale in Hyper-V con Hyper-V Manager o Windows PowerShell.","og_url":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/","og_site_name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","article_published_time":"2022-10-03T08:57:35+00:00","article_modified_time":"2022-10-03T08:58:14+00:00","og_image":[{"width":953,"height":620,"url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot-1.jpg","type":"image\/jpeg"}],"author":"Oliver Bennett","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Oliver Bennett","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#article","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/"},"author":{"name":"Oliver Bennett","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"headline":"Come disinstallare una macchina virtuale Hyper-V in Windows 10","datePublished":"2022-10-03T08:57:35+00:00","dateModified":"2022-10-03T08:58:14+00:00","mainEntityOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/"},"wordCount":323,"commentCount":0,"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot-1.jpg","articleSection":["Instructions","Windows PowerShell"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/","url":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/","name":"Come disinstallare una macchina virtuale Hyper-V in Windows 10","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#primaryimage"},"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot-1.jpg","datePublished":"2022-10-03T08:57:35+00:00","dateModified":"2022-10-03T08:58:14+00:00","author":{"@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"description":"Informazioni per l'inserimento di una macchina virtuale in Hyper-V con Hyper-V Manager o Windows PowerShell.","breadcrumb":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#primaryimage","url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot-1.jpg","contentUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/08\/screenshot-1.jpg","width":953,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/howtowindowsguides.com\/it\/come-disinstallare-una-macchina-virtuale-hyper-v-in-windows-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtowindowsguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come disinstallare una macchina virtuale Hyper-V in Windows 10"}]},{"@type":"WebSite","@id":"https:\/\/howtowindowsguides.com\/it\/#website","url":"https:\/\/howtowindowsguides.com\/it\/","name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtowindowsguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31","name":"Oliver Bennett","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","caption":"Oliver Bennett"},"url":"https:\/\/howtowindowsguides.com\/it\/author\/oliver\/"}]}},"_links":{"self":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/comments?post=1478"}],"version-history":[{"count":0,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media\/844"}],"wp:attachment":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media?parent=1478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/categories?post=1478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/tags?post=1478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}