{"id":1029,"date":"2022-08-18T14:11:40","date_gmt":"2022-08-18T14:11:40","guid":{"rendered":"http:\/\/howtowindowsguides.com\/?p=1029"},"modified":"2022-09-26T13:05:38","modified_gmt":"2022-09-26T13:05:38","slug":"come-attivare-o-disattivare-hyper-v-in-windows-10","status":"publish","type":"post","link":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/","title":{"rendered":"Come attivare o disattivare Hyper-V in Windows 10"},"content":{"rendered":"<p>Hyper-V consente di eseguire pi\u00f9 sistemi operativi come macchine virtuali in Windows. Il componente Hyper-V pu\u00f2 essere attivato o disattivato in diversi modi, tra cui la console Windows PowerShell, l&#8217;utilit\u00e0 della riga di comando DISM (Deployment Image Maintenance and Management Tool) e l&#8217;interfaccia grafica del Pannello di controllo.<\/p>\n<p>Prima di abilitare il componente Hyper-V, \u00e8 necessario verificare i seguenti requisiti:<\/p>\n<ul>\n<li>Windows 10 Corporate, Professional o Educational<\/li>\n<li>Processore a 64 bit con supporto per la traduzione degli indirizzi di livello 2 (SLAT)<\/li>\n<li>Il processore deve supportare la tecnologia di virtualizzazione (Intel VT-x o AMD-V).<\/li>\n<li>Il computer deve avere almeno 4 GB di RAM installata.<\/li>\n<\/ul>\n<p>Verificare inoltre che la tecnologia di virtualizzazione sia abilitata nel BIOS\/UEFI.<\/p>\n<h2>Come attivare e disattivare tramite Windows PowerShell<\/h2>\n<p>Il componente Hyper-V pu\u00f2 essere attivato tramite la console Windows PowerShell.<\/p>\n<p>Per abilitare il componente Hyper-V, aprire la console di Windows PowerShell come amministratore ed eseguire il seguente comando:<\/p>\n<blockquote><p><strong>Enable-WindowsOptionalFeature -Online -FeatureName Microsoft-Hyper-V -All<\/strong><\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-729\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_1-12.jpg\" alt=\"\" width=\"845\" height=\"412\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_1-12.jpg 845w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_1-12-300x146.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_1-12-768x374.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_1-12-820x400.jpg 820w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><meta itemprop=\"width\" content=\"845\"><meta itemprop=\"height\" content=\"412\"><\/span><\/p>\n<p>Riavviare il computer per completare l&#8217;installazione.<\/p>\n<p>Per disabilitare il componente Hyper-V, aprire la console di Windows PowerShell come amministratore ed eseguire il seguente comando:<\/p>\n<blockquote><p><strong>Disable-WindowsOptionalFeature -Online -FeatureName Microsoft-Hyper-V-All<\/strong><\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-725\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_2-13.jpg\" alt=\"\" width=\"835\" height=\"424\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_2-13.jpg 835w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_2-13-300x152.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_2-13-768x390.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_2-13-788x400.jpg 788w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><meta itemprop=\"width\" content=\"835\"><meta itemprop=\"height\" content=\"424\"><\/span><\/p>\n<p>Per completare l&#8217;operazione di disabilitazione del componente Hyper-V, \u00e8 necessario riavviare il computer.<\/p>\n<h2>Gestione di Hyper-V con DISM<\/h2>\n<p>Per abilitare il componente Hyper-V utilizzando DISM, eseguire la riga di comando come amministratore ed eseguire il seguente comando:<\/p>\n<blockquote><p><strong>dism.exe \/Online \/Enable-Feature:Microsoft-Hyper-V-All<\/strong><\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-733\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_3-12.jpg\" alt=\"\" width=\"979\" height=\"512\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_3-12.jpg 979w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_3-12-300x157.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_3-12-768x402.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_3-12-765x400.jpg 765w\" sizes=\"auto, (max-width: 979px) 100vw, 979px\" \/><meta itemprop=\"width\" content=\"979\"><meta itemprop=\"height\" content=\"512\"><\/span><\/p>\n<p>Riavviare Windows per completare l&#8217;operazione.<\/p>\n<p>Per disabilitare il componente Hyper-V utilizzando DISM, eseguire la riga di comando come amministratore ed eseguire il seguente comando:<\/p>\n<blockquote><p><strong>dism.exe \/Online \/Disabilita-Funzione:Microsoft-Hyper-V-All<\/strong><\/p><\/blockquote>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-737\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_4-11.jpg\" alt=\"\" width=\"979\" height=\"512\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_4-11.jpg 979w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_4-11-300x157.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_4-11-768x402.jpg 768w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_4-11-765x400.jpg 765w\" sizes=\"auto, (max-width: 979px) 100vw, 979px\" \/><meta itemprop=\"width\" content=\"979\"><meta itemprop=\"height\" content=\"512\"><\/span><\/p>\n<p>Riavviare Windows per completare l&#8217;operazione.<\/p>\n<h2>Attivazione nella finestra &#8220;Caratteristiche di Windows<\/h2>\n<p>Per abilitare il componente Hyper-V nella finestra &#8220;Windows-Features&#8221;, premere <mark><strong>Vincere + R<\/strong><\/mark> e inserire (copiare e incollare) <mark>OptionalFeatures<\/mark> nella finestra <strong>Esegui<\/strong> che si apre, quindi premere <mark><strong>Invio \u21b5<\/strong><\/mark>.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-741\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_5-11.jpg\" alt=\"\" width=\"399\" height=\"206\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_5-11.jpg 399w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_5-11-300x155.jpg 300w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><meta itemprop=\"width\" content=\"399\"><meta itemprop=\"height\" content=\"206\"><\/span><\/p>\n<p>Nella finestra &#8220;Windows-Features&#8221; che si apre, selezionate <strong>Hyper-V<\/strong> e fate clic su <mark>OK<\/mark>.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-745\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_6-11.jpg\" alt=\"\" width=\"415\" height=\"368\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_6-11.jpg 415w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_6-11-300x266.jpg 300w\" sizes=\"auto, (max-width: 415px) 100vw, 415px\" \/><meta itemprop=\"width\" content=\"415\"><meta itemprop=\"height\" content=\"368\"><\/span><\/p>\n<p>Una volta completata l&#8217;installazione, verr\u00e0 richiesto di riavviare il computer.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-749\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_7-8.jpg\" alt=\"\" width=\"658\" height=\"480\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_7-8.jpg 658w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_7-8-300x219.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_7-8-548x400.jpg 548w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><meta itemprop=\"width\" content=\"658\"><meta itemprop=\"height\" content=\"480\"><\/span><\/p>\n<p>Per disattivare il componente Hyper-V, nella finestra &#8220;Windows-Features&#8221;, disabilitare <strong>Hyper-V<\/strong> e fare clic su <mark>OK<\/mark>.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-753\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_8-8.jpg\" alt=\"\" width=\"415\" height=\"368\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_8-8.jpg 415w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_8-8-300x266.jpg 300w\" sizes=\"auto, (max-width: 415px) 100vw, 415px\" \/><meta itemprop=\"width\" content=\"415\"><meta itemprop=\"height\" content=\"368\"><\/span><\/p>\n<p>Una volta completata l&#8217;installazione, verr\u00e0 richiesto di riavviare il computer.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-757\" src=\"http:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_9-7.jpg\" alt=\"\" width=\"658\" height=\"480\"  srcset=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_9-7.jpg 658w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_9-7-300x219.jpg 300w, https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot_9-7-548x400.jpg 548w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><meta itemprop=\"width\" content=\"658\"><meta itemprop=\"height\" content=\"480\"><\/span><\/p>\n<p>Utilizzando i passaggi sopra descritti, \u00e8 possibile abilitare o disabilitare il componente Hyper-V.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hyper-V consente di eseguire pi\u00f9 sistemi operativi come macchine virtuali in Windows. Il componente Hyper-V pu\u00f2 essere attivato o disattivato in diversi modi, tra cui la console Windows PowerShell, l&#8217;utilit\u00e0 della riga di comando DISM (Deployment Image Maintenance and Management Tool) e l&#8217;interfaccia grafica del Pannello di controllo. Prima di abilitare il componente Hyper-V, \u00e8 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,43],"tags":[],"class_list":["post-1029","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-istruzioni","category-windows-powershell-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come attivare o disattivare Hyper-V in Windows 10<\/title>\n<meta name=\"description\" content=\"Questo articolo mostra come attivare o disattivare la virtualizzazione di Hyper-V (un componente) in Windows 10.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come attivare o disattivare Hyper-V in Windows 10\" \/>\n<meta property=\"og:description\" content=\"Questo articolo mostra come attivare o disattivare la virtualizzazione di Hyper-V (un componente) in Windows 10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T14:11:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-26T13:05:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1044\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oliver Bennett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oliver Bennett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/\"},\"author\":{\"name\":\"Oliver Bennett\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"headline\":\"Come attivare o disattivare Hyper-V in Windows 10\",\"datePublished\":\"2022-08-18T14:11:40+00:00\",\"dateModified\":\"2022-09-26T13:05:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/\"},\"wordCount\":361,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/screenshot-13.jpg\",\"articleSection\":[\"Istruzioni\",\"Windows PowerShell\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/\",\"name\":\"Come attivare o disattivare Hyper-V in Windows 10\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/screenshot-13.jpg\",\"datePublished\":\"2022-08-18T14:11:40+00:00\",\"dateModified\":\"2022-09-26T13:05:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\"},\"description\":\"Questo articolo mostra come attivare o disattivare la virtualizzazione di Hyper-V (un componente) in Windows 10.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/screenshot-13.jpg\",\"contentUrl\":\"https:\\\/\\\/howtowindowsguides.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/screenshot-13.jpg\",\"width\":1044,\"height\":639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/come-attivare-o-disattivare-hyper-v-in-windows-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come attivare o disattivare Hyper-V in Windows 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/\",\"name\":\"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/#\\\/schema\\\/person\\\/03df0b7bcd704df0eb052e71cced1f31\",\"name\":\"Oliver Bennett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g\",\"caption\":\"Oliver Bennett\"},\"url\":\"https:\\\/\\\/howtowindowsguides.com\\\/it\\\/author\\\/oliver\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come attivare o disattivare Hyper-V in Windows 10","description":"Questo articolo mostra come attivare o disattivare la virtualizzazione di Hyper-V (un componente) in Windows 10.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/","og_locale":"it_IT","og_type":"article","og_title":"Come attivare o disattivare Hyper-V in Windows 10","og_description":"Questo articolo mostra come attivare o disattivare la virtualizzazione di Hyper-V (un componente) in Windows 10.","og_url":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/","og_site_name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","article_published_time":"2022-08-18T14:11:40+00:00","article_modified_time":"2022-09-26T13:05:38+00:00","og_image":[{"width":1044,"height":639,"url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot-13.jpg","type":"image\/jpeg"}],"author":"Oliver Bennett","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Oliver Bennett","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#article","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/"},"author":{"name":"Oliver Bennett","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"headline":"Come attivare o disattivare Hyper-V in Windows 10","datePublished":"2022-08-18T14:11:40+00:00","dateModified":"2022-09-26T13:05:38+00:00","mainEntityOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/"},"wordCount":361,"commentCount":0,"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot-13.jpg","articleSection":["Istruzioni","Windows PowerShell"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/","url":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/","name":"Come attivare o disattivare Hyper-V in Windows 10","isPartOf":{"@id":"https:\/\/howtowindowsguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#primaryimage"},"image":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot-13.jpg","datePublished":"2022-08-18T14:11:40+00:00","dateModified":"2022-09-26T13:05:38+00:00","author":{"@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31"},"description":"Questo articolo mostra come attivare o disattivare la virtualizzazione di Hyper-V (un componente) in Windows 10.","breadcrumb":{"@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#primaryimage","url":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot-13.jpg","contentUrl":"https:\/\/howtowindowsguides.com\/wp-content\/uploads\/2022\/07\/screenshot-13.jpg","width":1044,"height":639},{"@type":"BreadcrumbList","@id":"https:\/\/howtowindowsguides.com\/it\/come-attivare-o-disattivare-hyper-v-in-windows-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtowindowsguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come attivare o disattivare Hyper-V in Windows 10"}]},{"@type":"WebSite","@id":"https:\/\/howtowindowsguides.com\/it\/#website","url":"https:\/\/howtowindowsguides.com\/it\/","name":"Windows 10, novit\u00e0 Microsoft, recensioni di dispositivi, registro e tweak","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtowindowsguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/howtowindowsguides.com\/it\/#\/schema\/person\/03df0b7bcd704df0eb052e71cced1f31","name":"Oliver Bennett","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35962e2f03ed8ae5009bc0d380978939bb83cd9684ab3e1ce4b54dd58a40599e?s=96&d=mm&r=g","caption":"Oliver Bennett"},"url":"https:\/\/howtowindowsguides.com\/it\/author\/oliver\/"}]}},"_links":{"self":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/comments?post=1029"}],"version-history":[{"count":0,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/posts\/1029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/media?parent=1029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/categories?post=1029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtowindowsguides.com\/it\/wp-json\/wp\/v2\/tags?post=1029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}